{"id":22,"date":"2021-10-12T20:34:14","date_gmt":"2021-10-12T20:34:14","guid":{"rendered":"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/?post_type=artista&#038;p=22"},"modified":"2022-03-04T18:59:36","modified_gmt":"2022-03-04T18:59:36","slug":"tsuchiya-koitsu-%e5%9c%9f%e5%b1%8b%e5%85%89%e9%80%b8-1870-1949","status":"publish","type":"artista","link":"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/artista\/tsuchiya-koitsu-%e5%9c%9f%e5%b1%8b%e5%85%89%e9%80%b8-1870-1949\/","title":{"rendered":"Tsuchiya K\u014ditsu \u571f\u5c4b\u5149\u9038 (1870\u20131949)"},"content":{"rendered":"\n<p>Se estableci\u00f3 desde muy joven en Tokio, donde estudi\u00f3 con el maestro de <em><a class=\"enlace-grabado\" href=\"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/grabado-moderno\/el-nuevo-grabado-y-el-grabado-creativo\/\">ukiyo-e<\/a><\/em> Kobayashi Kiyochika, junto al que mantuvo una relaci\u00f3n profesional muy estrecha. Un gran volumen de su producci\u00f3n inicial fue xilogr\u00e1fica y se relacionaba con im\u00e1genes de la guerra sino-japonesa de 1894\u201395, aunque tambi\u00e9n tiene una producci\u00f3n litogr\u00e1fica de importancia. Comenz\u00f3 su trabajo con la casa <a class=\"enlace-grabado\" href=\"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/grabado-moderno\/watanabe-shozaburo-%e6%b8%a1%e8%be%ba%e5%ba%84%e4%b8%89%e9%83%8e-1885-1962\/\">Watanabe<\/a> en 1931, concentr\u00e1ndose en temas de paisaje, colaborando igualmente en el dise\u00f1o de estampas para otros talleres editoriales.<\/p>\n","protected":false},"featured_media":23,"template":"","class_list":["post-22","artista","type-artista","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tsuchiya K\u014ditsu \u571f\u5c4b\u5149\u9038 (1870\u20131949) - El nuevo grabado japon\u00e9s (shin-hanga) en la colecci\u00f3n de la Casa Popenoe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/artista\/tsuchiya-koitsu-\u571f\u5c4b\u5149\u9038-1870-1949\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tsuchiya K\u014ditsu \u571f\u5c4b\u5149\u9038 (1870\u20131949) - El nuevo grabado japon\u00e9s (shin-hanga) en la colecci\u00f3n de la Casa Popenoe\" \/>\n<meta property=\"og:description\" content=\"Se estableci\u00f3 desde muy joven en Tokio, donde estudi\u00f3 con el maestro de ukiyo-e Kobayashi Kiyochika, junto al que mantuvo una relaci\u00f3n profesional muy estrecha. Un gran volumen de su producci\u00f3n inicial fue xilogr\u00e1fica y se relacionaba con im\u00e1genes de la guerra sino-japonesa de 1894\u201395, aunque tambi\u00e9n tiene una producci\u00f3n litogr\u00e1fica de importancia. Comenz\u00f3 su&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/artista\/tsuchiya-koitsu-\u571f\u5c4b\u5149\u9038-1870-1949\/\" \/>\n<meta property=\"og:site_name\" content=\"El nuevo grabado japon\u00e9s (shin-hanga) en la colecci\u00f3n de la Casa Popenoe\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-04T18:59:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/wp-content\/uploads\/2021\/10\/Tsuchiya\u3000Koitsu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"459\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/#website\",\"url\":\"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/\",\"name\":\"El nuevo grabado japon\u00e9s (shin-hanga) en la colecci\u00f3n de la Casa Popenoe\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/artista\/tsuchiya-koitsu-%e5%9c%9f%e5%b1%8b%e5%85%89%e9%80%b8-1870-1949\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/wp-content\/uploads\/2021\/10\/Tsuchiya\u3000Koitsu.jpg\",\"contentUrl\":\"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/wp-content\/uploads\/2021\/10\/Tsuchiya\u3000Koitsu.jpg\",\"width\":459,\"height\":640},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/artista\/tsuchiya-koitsu-%e5%9c%9f%e5%b1%8b%e5%85%89%e9%80%b8-1870-1949\/#webpage\",\"url\":\"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/artista\/tsuchiya-koitsu-%e5%9c%9f%e5%b1%8b%e5%85%89%e9%80%b8-1870-1949\/\",\"name\":\"Tsuchiya K\u014ditsu \u571f\u5c4b\u5149\u9038 (1870\u20131949) - El nuevo grabado japon\u00e9s (shin-hanga) en la colecci\u00f3n de la Casa Popenoe\",\"isPartOf\":{\"@id\":\"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/artista\/tsuchiya-koitsu-%e5%9c%9f%e5%b1%8b%e5%85%89%e9%80%b8-1870-1949\/#primaryimage\"},\"datePublished\":\"2021-10-12T20:34:14+00:00\",\"dateModified\":\"2022-03-04T18:59:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/artista\/tsuchiya-koitsu-%e5%9c%9f%e5%b1%8b%e5%85%89%e9%80%b8-1870-1949\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/artista\/tsuchiya-koitsu-%e5%9c%9f%e5%b1%8b%e5%85%89%e9%80%b8-1870-1949\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/artista\/tsuchiya-koitsu-%e5%9c%9f%e5%b1%8b%e5%85%89%e9%80%b8-1870-1949\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Artistas\",\"item\":\"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/artista\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tsuchiya K\u014ditsu \u571f\u5c4b\u5149\u9038 (1870\u20131949)\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tsuchiya K\u014ditsu \u571f\u5c4b\u5149\u9038 (1870\u20131949) - El nuevo grabado japon\u00e9s (shin-hanga) en la colecci\u00f3n de la Casa Popenoe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/artista\/tsuchiya-koitsu-\u571f\u5c4b\u5149\u9038-1870-1949\/","og_locale":"es_ES","og_type":"article","og_title":"Tsuchiya K\u014ditsu \u571f\u5c4b\u5149\u9038 (1870\u20131949) - El nuevo grabado japon\u00e9s (shin-hanga) en la colecci\u00f3n de la Casa Popenoe","og_description":"Se estableci\u00f3 desde muy joven en Tokio, donde estudi\u00f3 con el maestro de ukiyo-e Kobayashi Kiyochika, junto al que mantuvo una relaci\u00f3n profesional muy estrecha. Un gran volumen de su producci\u00f3n inicial fue xilogr\u00e1fica y se relacionaba con im\u00e1genes de la guerra sino-japonesa de 1894\u201395, aunque tambi\u00e9n tiene una producci\u00f3n litogr\u00e1fica de importancia. Comenz\u00f3 su&hellip;","og_url":"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/artista\/tsuchiya-koitsu-\u571f\u5c4b\u5149\u9038-1870-1949\/","og_site_name":"El nuevo grabado japon\u00e9s (shin-hanga) en la colecci\u00f3n de la Casa Popenoe","article_modified_time":"2022-03-04T18:59:36+00:00","og_image":[{"width":459,"height":640,"url":"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/wp-content\/uploads\/2021\/10\/Tsuchiya\u3000Koitsu.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/#website","url":"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/","name":"El nuevo grabado japon\u00e9s (shin-hanga) en la colecci\u00f3n de la Casa Popenoe","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/artista\/tsuchiya-koitsu-%e5%9c%9f%e5%b1%8b%e5%85%89%e9%80%b8-1870-1949\/#primaryimage","inLanguage":"es","url":"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/wp-content\/uploads\/2021\/10\/Tsuchiya\u3000Koitsu.jpg","contentUrl":"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/wp-content\/uploads\/2021\/10\/Tsuchiya\u3000Koitsu.jpg","width":459,"height":640},{"@type":"WebPage","@id":"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/artista\/tsuchiya-koitsu-%e5%9c%9f%e5%b1%8b%e5%85%89%e9%80%b8-1870-1949\/#webpage","url":"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/artista\/tsuchiya-koitsu-%e5%9c%9f%e5%b1%8b%e5%85%89%e9%80%b8-1870-1949\/","name":"Tsuchiya K\u014ditsu \u571f\u5c4b\u5149\u9038 (1870\u20131949) - El nuevo grabado japon\u00e9s (shin-hanga) en la colecci\u00f3n de la Casa Popenoe","isPartOf":{"@id":"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/artista\/tsuchiya-koitsu-%e5%9c%9f%e5%b1%8b%e5%85%89%e9%80%b8-1870-1949\/#primaryimage"},"datePublished":"2021-10-12T20:34:14+00:00","dateModified":"2022-03-04T18:59:36+00:00","breadcrumb":{"@id":"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/artista\/tsuchiya-koitsu-%e5%9c%9f%e5%b1%8b%e5%85%89%e9%80%b8-1870-1949\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/artista\/tsuchiya-koitsu-%e5%9c%9f%e5%b1%8b%e5%85%89%e9%80%b8-1870-1949\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/artista\/tsuchiya-koitsu-%e5%9c%9f%e5%b1%8b%e5%85%89%e9%80%b8-1870-1949\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/"},{"@type":"ListItem","position":2,"name":"Artistas","item":"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/artista\/"},{"@type":"ListItem","position":3,"name":"Tsuchiya K\u014ditsu \u571f\u5c4b\u5149\u9038 (1870\u20131949)"}]}]}},"meta_box":[],"_links":{"self":[{"href":"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/wp-json\/wp\/v2\/artista\/22","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/wp-json\/wp\/v2\/artista"}],"about":[{"href":"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/wp-json\/wp\/v2\/types\/artista"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/wp-json\/wp\/v2\/media\/23"}],"wp:attachment":[{"href":"https:\/\/casapopenoe.ufm.edu\/grabados-japoneses\/wp-json\/wp\/v2\/media?parent=22"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}