{"id":156,"date":"2020-10-22T09:34:32","date_gmt":"2020-10-22T15:34:32","guid":{"rendered":"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/?post_type=grabado&#038;p=156"},"modified":"2020-11-06T09:14:27","modified_gmt":"2020-11-06T15:14:27","slug":"peterhof-palacio-imperial-de-verano-junto-a-san-petersburgo-rusia","status":"publish","type":"grabado","link":"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/grabado\/peterhof-palacio-imperial-de-verano-junto-a-san-petersburgo-rusia\/","title":{"rendered":"Peterhof, palacio imperial de verano, junto a San Petersburgo. Rusia."},"content":{"rendered":"\n<p>Grabado sobre papel<\/p>\n\n\n\n<p>circa 1770&nbsp;<\/p>\n\n\n\n<p>Colecci\u00f3n Casa Popenoe-Universidad Francisco Marroqu\u00edn<\/p>\n","protected":false},"featured_media":157,"template":"","categories":[],"tags":[8],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Peterhof, palacio imperial de verano, junto a San Petersburgo. Rusia. - Ciudades europeas | Casa Popenoe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/grabado\/peterhof-palacio-imperial-de-verano-junto-a-san-petersburgo-rusia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Peterhof, palacio imperial de verano, junto a San Petersburgo. Rusia. - Ciudades europeas | Casa Popenoe\" \/>\n<meta property=\"og:description\" content=\"Grabado sobre papel circa 1770&nbsp; Colecci\u00f3n Casa Popenoe-Universidad Francisco Marroqu\u00edn\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/grabado\/peterhof-palacio-imperial-de-verano-junto-a-san-petersburgo-rusia\/\" \/>\n<meta property=\"og:site_name\" content=\"Ciudades europeas | Casa Popenoe\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-06T15:14:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/wp-content\/uploads\/2020\/10\/28.-Russischer-Prospect_Peterhhoss-Palacio-Imperial-de-Campana-frente-a-Petersbourg-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1833\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/#website\",\"url\":\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/\",\"name\":\"Ciudades europeas | Casa Popenoe\",\"description\":\"Exposici\\u00f3n virtual de Casa Popenoe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/grabado\/peterhof-palacio-imperial-de-verano-junto-a-san-petersburgo-rusia\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/wp-content\/uploads\/2020\/10\/28.-Russischer-Prospect_Peterhhoss-Palacio-Imperial-de-Campana-frente-a-Petersbourg-scaled.jpg\",\"width\":2560,\"height\":1833},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/grabado\/peterhof-palacio-imperial-de-verano-junto-a-san-petersburgo-rusia\/#webpage\",\"url\":\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/grabado\/peterhof-palacio-imperial-de-verano-junto-a-san-petersburgo-rusia\/\",\"name\":\"Peterhof, palacio imperial de verano, junto a San Petersburgo. Rusia. - Ciudades europeas | Casa Popenoe\",\"isPartOf\":{\"@id\":\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/grabado\/peterhof-palacio-imperial-de-verano-junto-a-san-petersburgo-rusia\/#primaryimage\"},\"datePublished\":\"2020-10-22T15:34:32+00:00\",\"dateModified\":\"2020-11-06T15:14:27+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/grabado\/peterhof-palacio-imperial-de-verano-junto-a-san-petersburgo-rusia\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","meta_box":{"pais_grabado":"Rusia"},"_links":{"self":[{"href":"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/wp-json\/wp\/v2\/grabado\/156"}],"collection":[{"href":"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/wp-json\/wp\/v2\/grabado"}],"about":[{"href":"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/wp-json\/wp\/v2\/types\/grabado"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/wp-json\/wp\/v2\/media\/157"}],"wp:attachment":[{"href":"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/wp-json\/wp\/v2\/media?parent=156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/wp-json\/wp\/v2\/categories?post=156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/wp-json\/wp\/v2\/tags?post=156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}