{"id":154,"date":"2020-10-22T08:51:09","date_gmt":"2020-10-22T14:51:09","guid":{"rendered":"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/?post_type=grabado&#038;p=154"},"modified":"2020-11-06T10:45:46","modified_gmt":"2020-11-06T16:45:46","slug":"vista-perspectiva-del-portal-de-la-catedral-de-toledo-espana","status":"publish","type":"grabado","link":"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/grabado\/vista-perspectiva-del-portal-de-la-catedral-de-toledo-espana\/","title":{"rendered":"Vista perspectiva del portal de la Catedral de Toledo. Espa\u00f1a."},"content":{"rendered":"\n<p>Grabado sobre papel<\/p>\n\n\n\n<p>circa 1770&nbsp;<\/p>\n\n\n\n<p>Colecci\u00f3n Casa Popenoe-Universidad Francisco Marroqu\u00edn<\/p>\n","protected":false},"featured_media":155,"template":"","categories":[],"tags":[10],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vista perspectiva del portal de la Catedral de Toledo. Espa\u00f1a. - Ciudades europeas | Casa Popenoe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/grabado\/vista-perspectiva-del-portal-de-la-catedral-de-toledo-espana\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vista perspectiva del portal de la Catedral de Toledo. Espa\u00f1a. - Ciudades europeas | Casa Popenoe\" \/>\n<meta property=\"og:description\" content=\"Grabado sobre papel circa 1770&nbsp; Colecci\u00f3n Casa Popenoe-Universidad Francisco Marroqu\u00edn\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/grabado\/vista-perspectiva-del-portal-de-la-catedral-de-toledo-espana\/\" \/>\n<meta property=\"og:site_name\" content=\"Ciudades europeas | Casa Popenoe\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-06T16:45:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/wp-content\/uploads\/2020\/10\/20.Portail-de-LEglise-Cathedrale-de-Tolede_-Vista-perspectiva-de-la-Iglesia-Catedral-de-Toledo-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1824\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/#website\",\"url\":\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/\",\"name\":\"Ciudades europeas | Casa Popenoe\",\"description\":\"Exposici\\u00f3n virtual de Casa Popenoe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/grabado\/vista-perspectiva-del-portal-de-la-catedral-de-toledo-espana\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/wp-content\/uploads\/2020\/10\/20.Portail-de-LEglise-Cathedrale-de-Tolede_-Vista-perspectiva-de-la-Iglesia-Catedral-de-Toledo-2-scaled.jpg\",\"width\":2560,\"height\":1824},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/grabado\/vista-perspectiva-del-portal-de-la-catedral-de-toledo-espana\/#webpage\",\"url\":\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/grabado\/vista-perspectiva-del-portal-de-la-catedral-de-toledo-espana\/\",\"name\":\"Vista perspectiva del portal de la Catedral de Toledo. Espa\\u00f1a. - Ciudades europeas | Casa Popenoe\",\"isPartOf\":{\"@id\":\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/grabado\/vista-perspectiva-del-portal-de-la-catedral-de-toledo-espana\/#primaryimage\"},\"datePublished\":\"2020-10-22T14:51:09+00:00\",\"dateModified\":\"2020-11-06T16:45:46+00:00\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/grabado\/vista-perspectiva-del-portal-de-la-catedral-de-toledo-espana\/\"]}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","meta_box":{"pais_grabado":"Espa\u00f1a"},"_links":{"self":[{"href":"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/wp-json\/wp\/v2\/grabado\/154"}],"collection":[{"href":"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/wp-json\/wp\/v2\/grabado"}],"about":[{"href":"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/wp-json\/wp\/v2\/types\/grabado"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/wp-json\/wp\/v2\/media\/155"}],"wp:attachment":[{"href":"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/wp-json\/wp\/v2\/media?parent=154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/wp-json\/wp\/v2\/categories?post=154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/casapopenoe.ufm.edu\/ciudades-europeas\/wp-json\/wp\/v2\/tags?post=154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}